{"id":1322,"count":9,"description":"","link":"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/","name":"nefrocenter","slug":"nefrocenter","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>nefrocenter Archivi - Gruppo NefroCenter<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"nefrocenter Archivi - Gruppo NefroCenter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/\" \/>\n<meta property=\"og:site_name\" content=\"Gruppo NefroCenter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"nefrocenter Archivi - Gruppo NefroCenter","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"nefrocenter Archivi - Gruppo NefroCenter","og_url":"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/","og_site_name":"Gruppo NefroCenter","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/","url":"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/","name":"nefrocenter Archivi - Gruppo NefroCenter","isPartOf":{"@id":"https:\/\/www.nefrocenter.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nefrocenter.it\/en\/tag\/nefrocenter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.nefrocenter.it\/en\/"},{"@type":"ListItem","position":2,"name":"nefrocenter"}]},{"@type":"WebSite","@id":"https:\/\/www.nefrocenter.it\/en\/#website","url":"https:\/\/www.nefrocenter.it\/en\/","name":"Gruppo NefroCenter","description":"Primi perch\u00e9 iniziamo dalla ricerca","publisher":{"@id":"https:\/\/www.nefrocenter.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nefrocenter.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.nefrocenter.it\/en\/#organization","name":"NefroCenter","url":"https:\/\/www.nefrocenter.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.nefrocenter.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.nefrocenter.it\/wp-content\/uploads\/2021\/04\/logo_nefro.png","contentUrl":"https:\/\/www.nefrocenter.it\/wp-content\/uploads\/2021\/04\/logo_nefro.png","width":610,"height":134,"caption":"NefroCenter"},"image":{"@id":"https:\/\/www.nefrocenter.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NefrocenterNefrocenter\/","https:\/\/www.instagram.com\/nefrocenter_\/","https:\/\/www.youtube.com\/channel\/UCRMKh8Wpdt0st0JZxWnVcmg"]}]}},"_links":{"self":[{"href":"https:\/\/www.nefrocenter.it\/en\/wp-json\/wp\/v2\/tags\/1322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nefrocenter.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.nefrocenter.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.nefrocenter.it\/en\/wp-json\/wp\/v2\/posts?tags=1322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}